{"id":21,"date":"2019-03-14T16:46:36","date_gmt":"2019-03-14T16:46:36","guid":{"rendered":"https:\/\/martindaleco.com\/store\/?page_id=21"},"modified":"2025-09-25T16:37:36","modified_gmt":"2025-09-25T20:37:36","slug":"products","status":"publish","type":"page","link":"https:\/\/martindaleco.com\/store\/","title":{"rendered":"Products"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"21\" class=\"elementor elementor-21\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd73b8f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd73b8f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4bf75108\" data-id=\"4bf75108\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed0c997 elementor-widget elementor-widget-html\" data-id=\"ed0c997\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\r\n  document.addEventListener(\"DOMContentLoaded\", function (event) {\r\n    let translatorWrapper = document.querySelector(\".gtranslate_wrapper\");\r\n    translatorWrapper.style.display = \"unset !important\";\r\n  });\r\n<\/script>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2599d4c8 elementor-widget elementor-widget-heading\" data-id=\"2599d4c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Products<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-15722575\" data-id=\"15722575\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5de26da9 elementor-widget elementor-widget-shortcode\" data-id=\"5de26da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t\t<!-- Flexy Breadcrumb -->\r\n\t\t\t<div class=\"fbc fbc-page\">\r\n\r\n\t\t\t\t<!-- Breadcrumb wrapper -->\r\n\t\t\t\t<div class=\"fbc-wrap\">\r\n\r\n\t\t\t\t\t<!-- Ordered list-->\r\n\t\t\t\t\t<ol class=\"fbc-items\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\">\r\n\t\t\t\t\t\t            <li itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\">\r\n                <span itemprop=\"name\">\r\n                    <!-- Home Link -->\r\n                    <a itemprop=\"item\" href=\"https:\/\/martindaleco.com\/store\">\r\n                    \r\n                        Home                    <\/a>\r\n                <\/span>\r\n                <meta itemprop=\"position\" content=\"1\" \/><!-- Meta Position-->\r\n             <\/li><li><span class=\"fbc-separator\">|<\/span><\/li><li class=\"active\" itemprop=\"itemListElement\" itemscope itemtype=\"https:\/\/schema.org\/ListItem\"><span itemprop=\"name\" title=\"Products\">Products<\/span><meta itemprop=\"position\" content=\"2\" \/><\/li>\t\t\t\t\t<\/ol>\r\n\t\t\t\t\t<div class=\"clearfix\"><\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-268acee9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"268acee9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3de88988\" data-id=\"3de88988\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-454eeb0a elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"454eeb0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"70\" height=\"70\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2020\/02\/circular-saws-icon.png\" class=\"attachment-full size-full wp-image-13203\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Circular Saws &amp; Cutting Tools<\/h3><p class=\"elementor-image-box-description\">Saw blades, burs, and accessories you need to improve performance.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7560c5ba elementor-widget elementor-widget-marWooCat\" data-id=\"7560c5ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"marWooCat.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"marWooCatBox-elementor-widget\"><ul class=\"ast-flex last-two-half\"><li  class=\"ast-flex\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/high-speed-steel\/\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/05\/high-speed-steel.jpg\" alt=\"H.S.S. (High Speed Steel)\" \/><span class=\"category-title has-image\">H.S.S. (High Speed Steel)<\/span><\/a><\/li><li  class=\"ast-flex\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/solid-carbide\/\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/05\/solid-carbide.jpg\" alt=\"Solid Carbide\" \/><span class=\"category-title has-image\">Solid Carbide<\/span><\/a><\/li><li  class=\"ast-flex\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/carbide-tipped\/\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/05\/carbide-tipped.jpg\" alt=\"Carbide Tipped\" \/><span class=\"category-title has-image\">Carbide Tipped<\/span><\/a><\/li><li  class=\"ast-flex\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/custom-saws\/\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/12\/custom-saw-icon.jpg\" alt=\"Custom Saws\" \/><span class=\"category-title has-image\">Custom Saws<\/span><\/a><\/li><li  class=\"ast-flex\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/resharpening-services\/\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/06\/resharpening-services-old.jpg\" alt=\"Resharpening Services\" \/><span class=\"category-title has-image\">Resharpening Services<\/span><\/a><\/li><li  class=\"ast-flex\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/saw-arbors\/\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/05\/saw-arbors.jpg\" alt=\"Saw Arbors\" \/><span class=\"category-title has-image\">Saw Arbors<\/span><\/a><\/li><li  class=\"ast-flex\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-burs.pdf\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/03\/rotary-burs-1.jpg\" alt=\"Rotary Burs\" \/><span class=\"category-title has-image\">Rotary Burs<\/span><\/a><\/li><li  class=\"ast-flex\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/bitner-custom-tooling\/\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/05\/bitner-custom-tooling.jpg\" alt=\"Bitner Custom Tooling\" \/><span class=\"category-title has-image\">Bitner Custom Tooling<\/span><\/a><\/li><\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-698d5e7d\" data-id=\"698d5e7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5727eaef\" data-id=\"5727eaef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40c4dc06 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"40c4dc06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"86\" height=\"59\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/11\/Electric-Motor.png\" class=\"attachment-full size-full wp-image-12978\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">ELECTRIC motor repair<\/h3><p class=\"elementor-image-box-description\">Everything you need to keep motors running smoothly.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29270480 elementor-widget elementor-widget-marWooCat\" data-id=\"29270480\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"marWooCat.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"marWooCatBox-elementor-widget\"><ul class=\"ast-flex last-full\"><li  class=\"ast-flex\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-abrasives.pdf\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/05\/abrasives.jpg\" alt=\"Abrasives\" \/><span class=\"category-title has-image\">Abrasives<\/span><\/a><\/li><li  class=\"ast-flex\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-grinders.pdf\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2020\/03\/commutator-grinders.jpg\" alt=\"Commutator Grinders\" \/><span class=\"category-title has-image\">Commutator Grinders<\/span><\/a><\/li><li  class=\"ast-flex\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-undercutters.pdf\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2020\/08\/MODEL-K-MICA-MILLER-e1597691666420.jpg\" alt=\"Commutator Undercutters\" \/><span class=\"category-title has-image\">Commutator Undercutters<\/span><\/a><\/li><li  class=\"ast-flex\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-hand-tools.pdf\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/05\/electrical-hand-tools.jpg\" alt=\"Hand Tools\" \/><span class=\"category-title has-image\">Hand Tools<\/span><\/a><\/li><li  class=\"ast-flex\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-test-equipment.pdf\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/05\/electrical-test-equipment.jpg\" alt=\"Test Equipment\" \/><span class=\"category-title has-image\">Test Equipment<\/span><\/a><\/li><li  class=\"ast-flex\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-burs.pdf\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/05\/rotary-burs.jpg\" alt=\"Rotary Burs\" \/><span class=\"category-title has-image\">Rotary Burs<\/span><\/a><\/li><li  class=\"ast-flex\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-other.pdf\" ><img decoding=\"async\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/06\/Etcher_Utility-e1597005956953.jpg\" alt=\"Other Products\" \/><span class=\"category-title has-image\">Other Products<\/span><\/a><\/li><\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-dff8439 e-flex e-con-boxed e-con e-parent\" data-id=\"dff8439\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8136dce bdt-icon-type-image bdt-global-link-yes martindale-store-links elementor-widget__width-inherit elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"8136dce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\" onclick=\"window.open(&#039;https:\/\/martindaleco.com\/resources\/saw-selector\/&#039;, &#039;_self&#039;)\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img decoding=\"async\" width=\"54\" height=\"54\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/03\/search.png\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\tSaw <br \/>\nSelector\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a class=\"bdt-ep-advanced-icon-box-readmore\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26afb71 bdt-icon-type-image bdt-global-link-yes martindale-store-links elementor-widget__width-inherit elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"26afb71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\" onclick=\"window.open(&#039;https:\/\/martindaleco.com\/resources\/&#039;, &#039;_self&#039;)\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"64\" height=\"51\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/03\/resources.png\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\tResources\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a class=\"bdt-ep-advanced-icon-box-readmore\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b042a5 bdt-icon-type-image bdt-global-link-yes martindale-store-links elementor-widget__width-inherit elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"5b042a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\" onclick=\"window.open(&#039;https:\/\/martindaleco.com\/resources\/catalog\/&#039;, &#039;_self&#039;)\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"71\" height=\"61\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/03\/catalog.png\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\tCatalogs\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a class=\"bdt-ep-advanced-icon-box-readmore\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-714c36a bdt-icon-type-image bdt-global-link-yes martindale-store-links elementor-widget__width-inherit elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"714c36a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\" onclick=\"window.open(&#039;https:\/\/martindaleco.com\/quote-request\/&#039;, &#039;_self&#039;)\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"67\" height=\"65\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/03\/quote.png\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\tRequest <br \/>\nQuote\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a class=\"bdt-ep-advanced-icon-box-readmore\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2e506e bdt-icon-type-image bdt-global-link-yes martindale-store-links elementor-widget__width-inherit elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"f2e506e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\" onclick=\"window.open(&#039;https:\/\/martindaleco.com\/resources\/saw-distributors\/&#039;, &#039;_self&#039;)\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img decoding=\"async\" width=\"54\" height=\"54\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2019\/03\/search.png\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\t<p>Saw<br \/>Distributors<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a class=\"bdt-ep-advanced-icon-box-readmore\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e02555f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e02555f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d3bb31b\" data-id=\"d3bb31b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbb8bbd elementor-widget elementor-widget-image\" data-id=\"bbb8bbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/martindaleco.com\/resources\/24-hours-shipment\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1331\" height=\"768\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2025\/04\/MARTINDALE.png\" class=\"attachment-full size-full wp-image-17517\" alt=\"\" srcset=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2025\/04\/MARTINDALE.png 1331w, https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2025\/04\/MARTINDALE-300x173.png 300w, https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2025\/04\/MARTINDALE-1024x591.png 1024w, https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2025\/04\/MARTINDALE-768x443.png 768w, https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2025\/04\/MARTINDALE-600x346.png 600w\" sizes=\"(max-width: 1331px) 100vw, 1331px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b051892 elementor-widget elementor-widget-spacer\" data-id=\"b051892\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6178c7b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6178c7b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd905af\" data-id=\"bd905af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c7cc1e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c7cc1e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-125ad70\" data-id=\"125ad70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8720197 elementor-widget elementor-widget-heading\" data-id=\"8720197\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Martindale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b98a9d mart-footer-menu elementor-widget elementor-widget-bdt-navbar\" data-id=\"7b98a9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-navbar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-navbar-wrapper\">\n\t\t\t<nav class=\"bdt-navbar-container bdt-navbar bdt-navbar-transparent\" data-bdt-navbar=\"{&quot;align&quot;:&quot;left&quot;,&quot;delay-hide&quot;:800,&quot;duration&quot;:200}\" id=\"bdt-navbar-7b98a9d\">\n\t\t\t\t<ul class=\"bdt-navbar-nav \"><li style=\"\" data-id=\"13346\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-burs.pdf\">Rotary Burs<\/a><\/li><li style=\"\" data-id=\"13304\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/bitner-custom-tooling\/\">Bitner Custom Tooling<\/a><\/li><\/ul>\t\t\t<\/nav>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-651edd3\" data-id=\"651edd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc9c33c elementor-widget elementor-widget-heading\" data-id=\"fc9c33c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Circular Saws<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57f0bd9 mart-footer-menu elementor-widget elementor-widget-bdt-navbar\" data-id=\"57f0bd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-navbar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-navbar-wrapper\">\n\t\t\t<nav class=\"bdt-navbar-container bdt-navbar bdt-navbar-transparent\" data-bdt-navbar=\"{&quot;align&quot;:&quot;left&quot;,&quot;delay-hide&quot;:800,&quot;duration&quot;:200}\" id=\"bdt-navbar-57f0bd9\">\n\t\t\t\t<ul class=\"bdt-navbar-nav \"><li style=\"\" data-id=\"13299\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/high-speed-steel\/\">H.S.S. (High Speed Steel)<\/a><\/li><li style=\"\" data-id=\"13298\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/solid-carbide\/\">Solid Carbide<\/a><\/li><li style=\"\" data-id=\"13300\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/carbide-tipped\/\">Carbide Tipped<\/a><\/li><li style=\"\" data-id=\"13302\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/resharpening-services\/\">Resharpening Services<\/a><\/li><li style=\"\" data-id=\"13301\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/custom-saws\/\">Custom Saws<\/a><\/li><li style=\"\" data-id=\"13303\"><a href=\"https:\/\/martindaleco.com\/store\/product-category\/circular-saws-cutting-tools\/saw-arbors\/\">Saw Arbors<\/a><\/li><\/ul>\t\t\t<\/nav>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-15bba57\" data-id=\"15bba57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bd65c1 elementor-widget elementor-widget-heading\" data-id=\"4bd65c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Electric Motor Repair<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-417d543 mart-footer-menu elementor-widget elementor-widget-bdt-navbar\" data-id=\"417d543\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-navbar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-navbar-wrapper\">\n\t\t\t<nav class=\"bdt-navbar-container bdt-navbar bdt-navbar-transparent\" data-bdt-navbar=\"{&quot;align&quot;:&quot;left&quot;,&quot;delay-hide&quot;:800,&quot;duration&quot;:200}\" id=\"bdt-navbar-417d543\">\n\t\t\t\t<ul class=\"bdt-navbar-nav \"><li style=\"\" data-id=\"13339\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-abrasives.pdf\">Abrasives<\/a><\/li><li style=\"\" data-id=\"13340\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-grinders.pdf\">Commutator Grinders<\/a><\/li><li style=\"\" data-id=\"13341\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-undercutters.pdf\">Commutator Undercutters<\/a><\/li><li style=\"\" data-id=\"13342\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-hand-tools.pdf\">Hand Tools<\/a><\/li><li style=\"\" data-id=\"13343\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-test-equipment.pdf\">Test Equipment<\/a><\/li><li style=\"\" data-id=\"13344\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-burs.pdf\">Rotary Burs<\/a><\/li><li style=\"\" data-id=\"13345\"><a target=\"_blank\" href=\"https:\/\/martindaleco.com\/wp-content\/uploads\/2019\/05\/martindale-catalog-other.pdf\">Other Products<\/a><\/li><\/ul>\t\t\t<\/nav>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-36791a7\" data-id=\"36791a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-825931e elementor-widget elementor-widget-heading\" data-id=\"825931e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact Info<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94aa2c4 elementor-position-left mart-footer-contact-link elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"94aa2c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"21\" height=\"20\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2023\/10\/footer-map-pin.png\" class=\"attachment-full size-full wp-image-17109\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\"><a href=\"https:\/\/goo.gl\/maps\/bWeA8SpTtZiGa6qB6\" target=\"_blank\">1375 Hird Ave.Cleveland, OH 44107-3008<\/a><\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a882377 elementor-position-inline-start mart-footer-contact-link elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a882377\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"faseci martindale-mg-envelope-3\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href=\"mailto:sales@martindaleco.com\">sales@martindaleco.com<\/a>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84367f7 elementor-position-inline-start mart-footer-contact-link elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"84367f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i class=\"eci martindale-mg-phone\" aria-hidden=\"true\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href=\"tel:2165218567\">216-521-8567<\/a>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e3c9179 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e3c9179\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-749d802\" data-id=\"749d802\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f66bd3 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0f66bd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u00a9 2026. Martindale. All rights reserved.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dbb3974 mart-footer-logos\" data-id=\"dbb3974\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a1e8f7 elementor-widget elementor-widget-image\" data-id=\"6a1e8f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/martindaleco.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"59\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2025\/09\/martindale-footer-logo.png\" class=\"attachment-full size-full wp-image-17634\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-666a75a elementor-widget elementor-widget-image\" data-id=\"666a75a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"83\" height=\"61\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2025\/09\/footer-logo-seprator.png\" class=\"attachment-full size-full wp-image-17636\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1610743 elementor-widget elementor-widget-image\" data-id=\"1610743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/gayleesaws.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"163\" height=\"68\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2025\/09\/gaylee-footer-logo.png\" class=\"attachment-full size-full wp-image-17638\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-54e2224\" data-id=\"54e2224\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4635640 elementor-widget elementor-widget-image\" data-id=\"4635640\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"138\" height=\"45\" src=\"https:\/\/martindaleco.com\/store\/wp-content\/uploads\/sites\/6\/2025\/09\/made-in-usa.png\" class=\"attachment-large size-large wp-image-17640\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Products Circular Saws &amp; Cutting Tools Saw blades, burs, and accessories you need to improve performance. H.S.S. (High Speed Steel) Solid Carbide Carbide Tipped Custom Saws Resharpening Services Saw Arbors Rotary Burs Bitner Custom Tooling ELECTRIC motor repair Everything you need to keep motors running smoothly. Abrasives Commutator Grinders Commutator Undercutters Hand Tools Test Equipment [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"disabled","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-21","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/martindaleco.com\/store\/wp-json\/wp\/v2\/pages\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martindaleco.com\/store\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/martindaleco.com\/store\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/martindaleco.com\/store\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martindaleco.com\/store\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":5,"href":"https:\/\/martindaleco.com\/store\/wp-json\/wp\/v2\/pages\/21\/revisions"}],"predecessor-version":[{"id":17673,"href":"https:\/\/martindaleco.com\/store\/wp-json\/wp\/v2\/pages\/21\/revisions\/17673"}],"wp:attachment":[{"href":"https:\/\/martindaleco.com\/store\/wp-json\/wp\/v2\/media?parent=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}